{"id":11987,"date":"2026-05-13T14:51:50","date_gmt":"2026-05-13T11:51:50","guid":{"rendered":"https:\/\/m24press.com\/les-lions-etablissent-leur-programme-de-preparation-a-la-coupe-du-monde-trois-matches-amicaux-cruciaux-en-perspective\/"},"modified":"2026-05-13T14:51:50","modified_gmt":"2026-05-13T11:51:50","slug":"les-lions-etablissent-leur-programme-de-preparation-a-la-coupe-du-monde-trois-matches-amicaux-cruciaux-en-perspective","status":"publish","type":"post","link":"https:\/\/m24press.com\/fr\/les-lions-etablissent-leur-programme-de-preparation-a-la-coupe-du-monde-trois-matches-amicaux-cruciaux-en-perspective\/","title":{"rendered":"Les Lions \u00e9tablissent leur programme de pr\u00e9paration \u00e0 la Coupe du monde Trois matches amicaux cruciaux en perspective"},"content":{"rendered":"\n<p>La F\u00e9d\u00e9ration Royale Marocaine de Football a annonc\u00e9 le programme de pr\u00e9paration de l&rsquo;\u00e9quipe nationale marocaine en vue de la Coupe du Monde de la FIFA 2026, o\u00f9 les \u00ab\u00a0Lions de l&rsquo;Atlas\u00a0\u00bb joueront trois matches amicaux au cours de la p\u00e9riode \u00e0 venir.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trois matches avant la Coupe du monde<\/h2>\n\n\n\n<p>L&rsquo;\u00e9quipe nationale marocaine entre dans une phase importante de pr\u00e9paration \u00e0 la Coupe du monde, avec trois matchs amicaux contre le Burundi, Madagascar et la Norv\u00e8ge, entre mai et juin 2026.  <\/p>\n\n\n\n<p>Ces matches font partie du programme visant \u00e0 am\u00e9liorer la pr\u00e9paration de l&rsquo;\u00e9quipe nationale en vue de la Coupe du monde, qui se d\u00e9roulera pour la premi\u00e8re fois avec la participation de 48 \u00e9quipes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le match du Burundi \u00e0 huis clos<\/h2>\n\n\n\n<p>L&rsquo;\u00e9quipe nationale marocaine d\u00e9butera ses matches de pr\u00e9paration contre le Burundi, le 26 mai 2026. <\/p>\n\n\n\n<p>Le match se jouera au Complexe de football Mohammed VI, \u00e0 huis clos et sans supporters, dans le cadre d&rsquo;un test technique et tactique pour le staff technique en vue des prochaines \u00e9ch\u00e9ances.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Face \u00e0 Madagascar \u00e0 Rabat<\/h2>\n\n\n\n<p>Les Lions de l&rsquo;Atlas affronteront ensuite Madagascar le 2 juin 2026, \u00e0 partir de 18 heures.  <\/p>\n\n\n\n<p>Le match se d\u00e9roulera au stade Prince Moulay Abdallah de Rabat, dans le cadre d&rsquo;un nouveau match amical qui s&rsquo;inscrit dans la pr\u00e9paration de l&rsquo;\u00e9quipe nationale pour la Coupe du monde. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un bon test contre la Norv\u00e8ge \u00e0 New York<\/h2>\n\n\n\n<p>L&rsquo;\u00e9quipe nationale marocaine terminera son programme de matches amicaux par un match difficile contre la Norv\u00e8ge le 7 juin 2026. <\/p>\n\n\n\n<p>Le coup d&rsquo;envoi du match est pr\u00e9vu \u00e0 15 heures, heure locale, \u00e0 la Red Bull Arena de New York, aux \u00c9tats-Unis. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Programme de matches amicaux de l&rsquo;\u00e9quipe nationale marocaine<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Maroc vs Burundi : 26 mai 2026, Stade Mohammed VI, sans spectateurs.   <\/li>\n\n\n\n<li>Maroc vs Madagascar : 2 juin 2026, 18h, au stade Prince Moulay Abdallah de Rabat.   <\/li>\n\n\n\n<li>Maroc vs Norv\u00e8ge : 7 juin 2026, 15h, Red Bull Arena \u00e0 New York.   <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e9paratifs en cours pour la Coupe du monde<\/h2>\n\n\n\n<p>Ces matches s&rsquo;inscrivent dans le cadre de la volont\u00e9 de l&rsquo;\u00e9quipe nationale marocaine d&rsquo;aborder la Coupe du monde avec la meilleure pr\u00e9paration possible, en mettant l&rsquo;\u00e9quipe nationale \u00e0 l&rsquo;\u00e9preuve de diff\u00e9rentes \u00e9coles de football. <\/p>\n\n\n\n<p>Ces matches amicaux permettent \u00e9galement au staff technique d&rsquo;\u00e9valuer le niveau des joueurs et de finaliser les s\u00e9lections avant le d\u00e9but de la comp\u00e9tition mondiale. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La F\u00e9d\u00e9ration Royale Marocaine de Football a annonc\u00e9 le programme de pr\u00e9paration de l&rsquo;\u00e9quipe nationale marocaine en vue de la Coupe du Monde de la FIFA 2026, o\u00f9 les \u00ab\u00a0Lions de l&rsquo;Atlas\u00a0\u00bb joueront trois matches amicaux au cours de la p\u00e9riode \u00e0 venir. Trois matches avant la Coupe du monde L&rsquo;\u00e9quipe nationale marocaine entre dans &hellip;<\/p>\n","protected":false},"author":2,"featured_media":11985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-11987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-sportives"],"_links":{"self":[{"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/posts\/11987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/comments?post=11987"}],"version-history":[{"count":0,"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/posts\/11987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/media\/11985"}],"wp:attachment":[{"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/media?parent=11987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/categories?post=11987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/m24press.com\/fr\/wp-json\/wp\/v2\/tags?post=11987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}